{"id":78796,"date":"2017-12-11T20:02:46","date_gmt":"2017-12-11T20:02:46","guid":{"rendered":"https:\/\/es.wordpress.org\/plugins\/mapeapost\/"},"modified":"2018-01-17T20:04:16","modified_gmt":"2018-01-17T20:04:16","slug":"wp-mappost","status":"closed","type":"plugin","link":"https:\/\/wordpress.org\/plugins\/wp-mappost\/","author":15833592,"comment_status":"closed","ping_status":"closed","template":"","meta":{"version":"1.0.1","stable_tag":"1.0.1","tested":"4.9.29","requires":"3.0.1","requires_php":"","requires_plugins":"","header_name":"MapeaPost","header_author":"GlaucusSoft","header_description":"Mapea la geolocalizaci\u00f3n de las entradas del blog para mostrarlas en un mapa y enlazar los markers a la propia entrada","assets_banners_color":"","last_updated":"2018-01-17 20:04:16","external_support_url":"","external_repository_url":"","donate_link":"https:\/\/glaucussoft.com\/mapeapost\/","header_plugin_uri":"https:\/\/glaucussoft.com\/mapeapost","header_author_uri":"https:\/\/glaucussoft.com","rating":0,"author_block_rating":0,"active_installs":10,"downloads":1214,"num_ratings":0,"support_threads":0,"support_threads_resolved":0,"author_block_count":0,"sections":["description","installation","faq","changelog"],"tags":[],"upgrade_notice":{"1.0.1":"<p>Actualiza si tienes problemas al mostrar el mapa en tu sitio web<\/p>","1.0":"<p>Muestra tus post localizados en un mapa<\/p>"},"ratings":{"1":0,"2":0,"3":0,"4":0,"5":0},"assets_icons":{"icon-128x128.png":{"filename":"icon-128x128.png","revision":"1784976","resolution":"128x128","location":"assets"},"icon-256x256.png":{"filename":"icon-256x256.png","revision":"1784976","resolution":"256x256","location":"assets"}},"assets_banners":[],"assets_blueprints":{},"all_blocks":[],"tagged_versions":["1.0","1.0.1"],"block_files":[],"assets_screenshots":{"screenshot-1.PNG":{"filename":"screenshot-1.PNG","revision":"1784955","resolution":"1","location":"assets"},"screenshot-2.PNG":{"filename":"screenshot-2.PNG","revision":"1784978","resolution":"2","location":"assets"},"screenshot-3.png":{"filename":"screenshot-3.png","revision":"1804016","resolution":"3","location":"assets"}},"screenshots":{"1":"Esta captura de pantalla corresponde al mapa mostrando una entrada sobre el 'Restaurante Casa Jos\u00e9 Mar\u00eda' con una etiqueta\nde un 9","2":"Esta captura de pantalla corresponde con el panel lateral en la edici\u00f3n de un 'post' para introducir las coordenadas del marcador","3":"Esta captura de pantalla corresponde al panel de ajustes. Los n\u00fameros indican el recorrido para llegar hasta el panel."}},"plugin_section":[],"plugin_tags":[150541,150540,37067,150539],"plugin_category":[],"plugin_contributors":[],"plugin_business_model":[],"class_list":["post-78796","plugin","type-plugin","status-closed","hentry","plugin_tags-entrada","plugin_tags-localizacion","plugin_tags-mapa","plugin_tags-marcador","plugin_committers-glaucussoft"],"banners":[],"icons":{"svg":false,"icon":"https:\/\/s.w.org\/plugins\/geopattern-icon\/wp-mappost.svg","icon_2x":false,"generated":true},"screenshots":[{"src":"https:\/\/ps.w.org\/wp-mappost\/assets\/screenshot-1.PNG?rev=1784955","caption":"Esta captura de pantalla corresponde al mapa mostrando una entrada sobre el 'Restaurante Casa Jos\u00e9 Mar\u00eda' con una etiqueta\nde un 9"},{"src":"https:\/\/ps.w.org\/wp-mappost\/assets\/screenshot-2.PNG?rev=1784978","caption":"Esta captura de pantalla corresponde con el panel lateral en la edici\u00f3n de un 'post' para introducir las coordenadas del marcador"},{"src":"https:\/\/ps.w.org\/wp-mappost\/assets\/screenshot-3.png?rev=1804016","caption":"Esta captura de pantalla corresponde al panel de ajustes. Los n\u00fameros indican el recorrido para llegar hasta el panel."}],"raw_content":"<!--section=description-->\n<p>Este plugin permite que a\u00f1adas coordenadas geoespaciales a las entradas publicadas en tu blog. Puedes a\u00f1adir tambi\u00e9n un label (texto o n\u00famero) que se recomienda sea de pocos caracteres. A partir de un shortcode el plugin permite mostrar las entradas como marcadores en un mapa. En cada marcador aparecer\u00e1 el label que se haya indicado (o un punto en caso de dejarse vacio) por ello se recomienda que el label no sea muy extenso para que no sobresalga del marcador. El shortcode para generar el mapa permite filtrar por categorias de entradas, especificar el zoom inicial adem\u00e1s del centro del mapa. Al hacer click en un marcador se abrir\u00e1 un globo que contendr\u00e1 el t\u00edtulo de la entrada y un enlace para dirigirse a ella.\nPara m\u00e1s informaci\u00f3n visite nuestra <a href=\"https:\/\/glaucussoft.com\/mapeapost\/\">p\u00e1gina<\/a>.<\/p>\n\n<!--section=installation-->\n<p>M\u00e9todo de instalaci\u00f3n y configuraci\u00f3n del plugin<\/p>\n\n<ol>\n<li>Copia el contenido del zip en la ruta <code>\/wp-content\/plugins\/<\/code> de tu sitio.<\/li>\n<li>Activa el plugin en la vista de 'Plugins' en WordPress<\/li>\n<li>En Ajustes &gt; MapeaPost pega tu API key de GoogleMaps<\/li>\n<\/ol>\n\n<!--section=faq-->\n<dl>\n<dt>Installation Instructions<\/dt>\n<dd><p>M\u00e9todo de instalaci\u00f3n y configuraci\u00f3n del plugin<\/p>\n\n<ol>\n<li>Copia el contenido del zip en la ruta <code>\/wp-content\/plugins\/<\/code> de tu sitio.<\/li>\n<li>Activa el plugin en la vista de 'Plugins' en WordPress<\/li>\n<li>En Ajustes &gt; MapeaPost pega tu API key de GoogleMaps<\/li>\n<\/ol><\/dd>\n<dt>\u00bfC\u00f3mo puedo conseguir mi API key de GoogleMaps?<\/dt>\n<dd><p>Vaya al siguiente enlace: <a href=\"https:\/\/developers.google.com\/maps\/documentation\/javascript\/get-api-key?hl=ES\">https:\/\/developers.google.com\/maps\/documentation\/javascript\/get-api-key?hl=ES<\/a><\/p><\/dd>\n<dt>\u00bfComo creo un shortcode de mappost?<\/dt>\n<dd><p>Para crear el shortcode basta con pegar el siguiente c\u00f3digo en una p\u00e1gina o entrada de su sitio:\n[mappost_mapa]\nPara crear un shortcode de un mapa sobre las entradas de una categor\u00eda utilice el atributo 'categoria' y el nombre (slug) de la categor\u00eda. Por ejemplo:\n[mappost_mapa categoria=\"mi-categoria\"]\nPara crear un shortcode de un mapa centrado en una localizaci\u00f3n especifique el atributo 'centro' y para el zoom inicial utilize 'zoom'. Por ejemplo:\n[mappost_mapa centro=\"36.123456,-4.567890\" zoom=\"10\"]<\/p><\/dd>\n\n<\/dl>\n\n<!--section=changelog-->\n<h4>1.0.1<\/h4>\n\n<ul>\n<li>Correci\u00f3n de compatibilidad en ajustes<\/li>\n<\/ul>\n\n<h4>1.0<\/h4>\n\n<ul>\n<li>Primera versi\u00f3n liberada<\/li>\n<\/ul>","raw_excerpt":"Plugin que permite a\u00f1adir una geolocalizaci\u00f3n a las entradas del sitio para posteriormente ubicarlas en un mapa.","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin\/78796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin"}],"about":[{"href":"https:\/\/wordpress.org\/plugins\/wp-json\/wp\/v2\/types\/plugin"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.org\/plugins\/wp-json\/wp\/v2\/comments?post=78796"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.org\/plugins\/wp-json\/wporg\/v1\/users\/glaucussoft"}],"wp:attachment":[{"href":"https:\/\/wordpress.org\/plugins\/wp-json\/wp\/v2\/media?parent=78796"}],"wp:term":[{"taxonomy":"plugin_section","embeddable":true,"href":"https:\/\/wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_section?post=78796"},{"taxonomy":"plugin_tags","embeddable":true,"href":"https:\/\/wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_tags?post=78796"},{"taxonomy":"plugin_category","embeddable":true,"href":"https:\/\/wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_category?post=78796"},{"taxonomy":"plugin_contributors","embeddable":true,"href":"https:\/\/wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_contributors?post=78796"},{"taxonomy":"plugin_business_model","embeddable":true,"href":"https:\/\/wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_business_model?post=78796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}